{"id":6595,"date":"2012-06-06T12:58:43","date_gmt":"2012-06-06T10:58:43","guid":{"rendered":"http:\/\/nydalen.idrett.no\/wordpress\/wp-content\/uploads\/2012\/06\/WelcomeToLA.jpg"},"modified":"2012-06-06T12:58:43","modified_gmt":"2012-06-06T10:58:43","slug":"welcometola-2","status":"inherit","type":"attachment","link":"https:\/\/nydalen.idrett.no\/orientering\/2012\/06\/06\/rapport-fra-ungdomssamling-pa-budor\/welcometola-2\/","title":{"rendered":"WelcomeToLA"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6595","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nydalen.idrett.no\/orientering\/wp-content\/uploads\/2012\/06\/WelcomeToLA-e1338980364445.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/nydalen.idrett.no\/orientering\/wp-content\/uploads\/2012\/06\/WelcomeToLA-e1338980364445.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"300","height":"195","hwstring_small":"height='83' width='128'","file":"2012\/06\/WelcomeToLA-e1338980364445.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":6586,"source_url":"https:\/\/nydalen.idrett.no\/orientering\/wp-content\/uploads\/2012\/06\/WelcomeToLA-e1338980364445.jpg","_links":{"self":[{"href":"https:\/\/nydalen.idrett.no\/orientering\/wp-json\/wp\/v2\/media\/6595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nydalen.idrett.no\/orientering\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nydalen.idrett.no\/orientering\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nydalen.idrett.no\/orientering\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nydalen.idrett.no\/orientering\/wp-json\/wp\/v2\/comments?post=6595"}]}}